{"id":15,"date":"2024-04-18T08:19:23","date_gmt":"2024-04-18T08:19:23","guid":{"rendered":"http:\/\/localhost:8000\/?page_id=15"},"modified":"2024-05-21T17:20:48","modified_gmt":"2024-05-21T17:20:48","slug":"contact","status":"publish","type":"page","link":"https:\/\/bartengroup.com\/zh\/contact\/","title":{"rendered":"\u8054\u7cfb\u65b9\u5f0f"},"content":{"rendered":"<div class=\"wp-block-columns alignfull is-layout-flex wp-container-core-columns-is-layout-1 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div style=\"width: 100%\"><iframe loading=\"lazy\" width=\"100%\" height=\"400\" frameborder=\"0\" scrolling=\"no\" marginheight=\"0\" marginwidth=\"0\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d3988.745157896619!2d103.75551945905436!3d1.3289343851681004!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x31da11002c4fb701%3A0x97cf43b671595484!2sBarten%20Resources%20Pte%20Ltd!5e0!3m2!1sen!2ssg!4v1713757919254!5m2!1sen!2ssg\"><\/iframe><\/div>\n\n\n\n<p><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns container is-layout-flex wp-container-core-columns-is-layout-3 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading hestia-title\">\u7ed9\u6211\u4eec\u7559\u8a00<\/h2>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"forminator-guttenberg\"><div class=\"forminator-ui forminator-custom-form forminator-custom-form-146 forminator-design--default  forminator_ajax\" data-forminator-render=\"0\" data-form=\"forminator-module-146\" data-uid=\"6a97b09180aee\"><br\/><\/div><form\n\t\t\t\tid=\"forminator-module-146\"\n\t\t\t\tclass=\"forminator-ui forminator-custom-form forminator-custom-form-146 forminator-design--default  forminator_ajax\"\n\t\t\t\tmethod=\"post\"\n\t\t\t\tdata-forminator-render=\"0\"\n\t\t\t\tdata-form-id=\"146\"\n\t\t\t\t\n\t\t\t\tdata-design=\"default\"\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\tdata-grid=\"open\"\n\t\t\t\t\n\t\t\t\t\n\t\t\t\tstyle=\"display: none;\"\n\t\t\t\t\n\t\t\t\tdata-uid=\"6a97b09180aee\" action=\"\"\n\t\t\t><div role=\"alert\" aria-live=\"polite\" class=\"forminator-response-message forminator-error\" aria-hidden=\"true\"><\/div><div class=\"forminator-row\"><div id=\"name-1\" class=\"forminator-field-name forminator-col forminator-col-12\"><div class=\"forminator-field\"><label for=\"forminator-field-name-1_6a97b09180aee\" id=\"forminator-field-name-1_6a97b09180aee-label\" class=\"forminator-label\">\u540d\u79f0 <span class=\"forminator-required\">*<\/span><\/label><input type=\"text\" name=\"name-1\" value=\"\" placeholder=\"E.g. John\" id=\"forminator-field-name-1_6a97b09180aee\" class=\"forminator-input forminator-name--field\" aria-required=\"true\" \/><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"text-1\" class=\"forminator-field-text forminator-col forminator-col-12\"><div class=\"forminator-field\"><label for=\"forminator-field-text-1_6a97b09180aee\" id=\"forminator-field-text-1_6a97b09180aee-label\" class=\"forminator-label\">\u516c\u53f8 <span class=\"forminator-required\">*<\/span><\/label><input type=\"text\" name=\"text-1\" value=\"\" placeholder=\"E.g. ABC Co.\" id=\"forminator-field-text-1_6a97b09180aee\" class=\"forminator-input forminator-name--field\" data-required=\"1\" \/><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"address-1\" class=\"forminator-field-address forminator-col forminator-col-12\"><div class=\"forminator-row\" data-multiple=\"false\"><div id=\"address-1-country\" class=\"forminator-col forminator-col-12\"><div class=\"forminator-field\"><label for=\"forminator-field-146__field--address-1-country_6a97b09180aee\" id=\"forminator-field-146__field--address-1-country_6a97b09180aee-label\" class=\"forminator-label\">\u56fd\u5bb6 <span class=\"forminator-required\">*<\/span><\/label><select name=\"address-1-country\" id=\"forminator-field-146__field--address-1-country_6a97b09180aee\" class=\"forminator-select2\" data-search=\"true\" data-placeholder=\"Select country\" data-default-value=\"\"><option value=\"\" data-country-code=\"\" selected=\"selected\"><\/option><option value=\"Afghanistan\" data-country-code=\"AF\" >Afghanistan<\/option><option value=\"Albania\" data-country-code=\"AL\" >Albania<\/option><option value=\"Algeria\" data-country-code=\"DZ\" >Algeria<\/option><option value=\"American Samoa\" data-country-code=\"AS\" >American Samoa<\/option><option value=\"Andorra\" data-country-code=\"AD\" >Andorra<\/option><option value=\"Angola\" data-country-code=\"AO\" >Angola<\/option><option value=\"Anguilla\" data-country-code=\"AI\" >Anguilla<\/option><option value=\"Antarctica\" data-country-code=\"AQ\" >Antarctica<\/option><option value=\"Antigua and Barbuda\" data-country-code=\"AG\" >Antigua and Barbuda<\/option><option value=\"Argentina\" data-country-code=\"AR\" >Argentina<\/option><option value=\"Armenia\" data-country-code=\"AM\" >Armenia<\/option><option value=\"Australia\" data-country-code=\"AU\" >Australia<\/option><option value=\"Aruba\" data-country-code=\"AW\" >Aruba<\/option><option value=\"Austria\" data-country-code=\"AT\" >Austria<\/option><option value=\"Azerbaijan\" data-country-code=\"AZ\" >Azerbaijan<\/option><option value=\"Bahamas\" data-country-code=\"BS\" >Bahamas<\/option><option value=\"Bahrain\" data-country-code=\"BH\" >Bahrain<\/option><option value=\"Bangladesh\" data-country-code=\"BD\" >Bangladesh<\/option><option value=\"Barbados\" data-country-code=\"BB\" >Barbados<\/option><option value=\"Belarus\" data-country-code=\"BY\" >Belarus<\/option><option value=\"Belgium\" data-country-code=\"BE\" >Belgium<\/option><option value=\"Belize\" data-country-code=\"BZ\" >Belize<\/option><option value=\"Benin\" data-country-code=\"BJ\" >Benin<\/option><option value=\"Bermuda\" data-country-code=\"BM\" >Bermuda<\/option><option value=\"Bhutan\" data-country-code=\"BT\" >Bhutan<\/option><option value=\"Bolivia\" data-country-code=\"BO\" >Bolivia<\/option><option value=\"Bosnia and Herzegovina\" data-country-code=\"BA\" >Bosnia and Herzegovina<\/option><option value=\"Botswana\" data-country-code=\"BW\" >Botswana<\/option><option value=\"Bouvet Island\" data-country-code=\"BV\" >Bouvet Island<\/option><option value=\"Brazil\" data-country-code=\"BR\" >Brazil<\/option><option value=\"British Indian Ocean Territory\" data-country-code=\"IO\" >British Indian Ocean Territory<\/option><option value=\"Brunei\" data-country-code=\"BN\" >Brunei<\/option><option value=\"Bulgaria\" data-country-code=\"BG\" >Bulgaria<\/option><option value=\"Burkina Faso\" data-country-code=\"BF\" >Burkina Faso<\/option><option value=\"Burundi\" data-country-code=\"BI\" >Burundi<\/option><option value=\"Cambodia\" data-country-code=\"KH\" >\u67ec\u57d4\u5be8<\/option><option value=\"Cameroon\" data-country-code=\"CM\" >Cameroon<\/option><option value=\"Canada\" data-country-code=\"CA\" >Canada<\/option><option value=\"Cabo Verde\" data-country-code=\"CV\" >Cabo Verde<\/option><option value=\"Cayman Islands\" data-country-code=\"KY\" >Cayman Islands<\/option><option value=\"Central African Republic\" data-country-code=\"CF\" >Central African Republic<\/option><option value=\"Chad\" data-country-code=\"TD\" >Chad<\/option><option value=\"Chile\" data-country-code=\"CL\" >Chile<\/option><option value=\"China, People's Republic of\" data-country-code=\"CN\" >China, People's Republic of<\/option><option value=\"Christmas Island\" data-country-code=\"CX\" >Christmas Island<\/option><option value=\"Cocos Islands\" data-country-code=\"CC\" >Cocos Islands<\/option><option value=\"Colombia\" data-country-code=\"CO\" >Colombia<\/option><option value=\"Comoros\" data-country-code=\"KM\" >Comoros<\/option><option value=\"Congo, Democratic Republic of the\" data-country-code=\"CD\" >Congo, Democratic Republic of the<\/option><option value=\"Congo, Republic of the\" data-country-code=\"CG\" >Congo, Republic of the<\/option><option value=\"Cook Islands\" data-country-code=\"CK\" >Cook Islands<\/option><option value=\"Costa Rica\" data-country-code=\"CR\" >Costa Rica<\/option><option value=\"C\u00f4te d'Ivoire\" data-country-code=\"CI\" >C\u00f4te d'Ivoire<\/option><option value=\"Croatia\" data-country-code=\"HR\" >Croatia<\/option><option value=\"Cuba\" data-country-code=\"CU\" >Cuba<\/option><option value=\"Cura\u00e7ao\" data-country-code=\"CW\" >Cura\u00e7ao<\/option><option value=\"Cyprus\" data-country-code=\"CY\" >Cyprus<\/option><option value=\"Czech Republic\" data-country-code=\"CZ\" >Czech Republic<\/option><option value=\"Denmark\" data-country-code=\"DK\" >Denmark<\/option><option value=\"Djibouti\" data-country-code=\"DJ\" >Djibouti<\/option><option value=\"Dominica\" data-country-code=\"DM\" >Dominica<\/option><option value=\"Dominican Republic\" data-country-code=\"DO\" >Dominican Republic<\/option><option value=\"East Timor\" data-country-code=\"TL\" >East Timor<\/option><option value=\"Ecuador\" data-country-code=\"EC\" >Ecuador<\/option><option value=\"Egypt\" data-country-code=\"EG\" >Egypt<\/option><option value=\"El Salvador\" data-country-code=\"SV\" >El Salvador<\/option><option value=\"Equatorial Guinea\" data-country-code=\"GQ\" >Equatorial Guinea<\/option><option value=\"Eritrea\" data-country-code=\"ER\" >Eritrea<\/option><option value=\"Estonia\" data-country-code=\"EE\" >Estonia<\/option><option value=\"Ethiopia\" data-country-code=\"ET\" >Ethiopia<\/option><option value=\"Falkland Islands\" data-country-code=\"FK\" >Falkland Islands<\/option><option value=\"Faroe Islands\" data-country-code=\"FO\" >Faroe Islands<\/option><option value=\"Fiji\" data-country-code=\"FJ\" >Fiji<\/option><option value=\"Finland\" data-country-code=\"FI\" >Finland<\/option><option value=\"France\" data-country-code=\"FR\" >France<\/option><option value=\"France, Metropolitan\" data-country-code=\"FX\" >France, Metropolitan<\/option><option value=\"French Guiana\" data-country-code=\"GF\" >French Guiana<\/option><option value=\"French Polynesia\" data-country-code=\"PF\" >French Polynesia<\/option><option value=\"French South Territories\" data-country-code=\"TF\" >French South Territories<\/option><option value=\"Gabon\" data-country-code=\"GA\" >Gabon<\/option><option value=\"Gambia\" data-country-code=\"GM\" >Gambia<\/option><option value=\"Georgia\" data-country-code=\"GE\" >Georgia<\/option><option value=\"Germany\" data-country-code=\"DE\" >Germany<\/option><option value=\"Guernsey\" data-country-code=\"GG\" >Guernsey<\/option><option value=\"Ghana\" data-country-code=\"GH\" >Ghana<\/option><option value=\"Gibraltar\" data-country-code=\"GI\" >Gibraltar<\/option><option value=\"Greece\" data-country-code=\"GR\" >Greece<\/option><option value=\"Greenland\" data-country-code=\"GL\" >Greenland<\/option><option value=\"Grenada\" data-country-code=\"GD\" >Grenada<\/option><option value=\"Guadeloupe\" data-country-code=\"GP\" >Guadeloupe<\/option><option value=\"Guam\" data-country-code=\"GU\" >Guam<\/option><option value=\"Guatemala\" data-country-code=\"GT\" >Guatemala<\/option><option value=\"Guinea\" data-country-code=\"GN\" >Guinea<\/option><option value=\"Guinea-Bissau\" data-country-code=\"GW\" >Guinea-Bissau<\/option><option value=\"Guyana\" data-country-code=\"GY\" >Guyana<\/option><option value=\"Haiti\" data-country-code=\"HT\" >Haiti<\/option><option value=\"Heard Island And Mcdonald Island\" data-country-code=\"HM\" >Heard Island And Mcdonald Island<\/option><option value=\"Honduras\" data-country-code=\"HN\" >Honduras<\/option><option value=\"Hong Kong\" data-country-code=\"HK\" >Hong Kong<\/option><option value=\"Hungary\" data-country-code=\"HU\" >Hungary<\/option><option value=\"Iceland\" data-country-code=\"IS\" >Iceland<\/option><option value=\"India\" data-country-code=\"IN\" >\u5370\u5ea6<\/option><option value=\"Indonesia\" data-country-code=\"ID\" >\u5370\u5ea6\u5c3c\u897f\u4e9a<\/option><option value=\"Iran\" data-country-code=\"IR\" >Iran<\/option><option value=\"Iraq\" data-country-code=\"IQ\" >Iraq<\/option><option value=\"Ireland\" data-country-code=\"IE\" >Ireland<\/option><option value=\"Israel\" data-country-code=\"IL\" >Israel<\/option><option value=\"Italy\" data-country-code=\"IT\" >Italy<\/option><option value=\"Jamaica\" data-country-code=\"JM\" >Jamaica<\/option><option value=\"Japan\" data-country-code=\"JP\" >Japan<\/option><option value=\"Jersey\" data-country-code=\"JE\" >Jersey<\/option><option value=\"Johnston Island\" data-country-code=\"JT\" >Johnston Island<\/option><option value=\"Jordan\" data-country-code=\"JO\" >Jordan<\/option><option value=\"Kazakhstan\" data-country-code=\"KZ\" >Kazakhstan<\/option><option value=\"Kenya\" data-country-code=\"KE\" >Kenya<\/option><option value=\"Kiribati\" data-country-code=\"KI\" >Kiribati<\/option><option value=\"Korea, Democratic People's Republic of\" data-country-code=\"KP\" >Korea, Democratic People's Republic of<\/option><option value=\"Korea, Republic of\" data-country-code=\"KR\" >Korea, Republic of<\/option><option value=\"Kosovo\" data-country-code=\"XK\" >Kosovo<\/option><option value=\"Kuwait\" data-country-code=\"KW\" >Kuwait<\/option><option value=\"Kyrgyzstan\" data-country-code=\"KG\" >Kyrgyzstan<\/option><option value=\"Lao People's Democratic Republic\" data-country-code=\"LA\" >Lao People's Democratic Republic<\/option><option value=\"Latvia\" data-country-code=\"LV\" >Latvia<\/option><option value=\"Lebanon\" data-country-code=\"LB\" >Lebanon<\/option><option value=\"Lesotho\" data-country-code=\"LS\" >Lesotho<\/option><option value=\"Liberia\" data-country-code=\"LR\" >Liberia<\/option><option value=\"Libya\" data-country-code=\"LY\" >Libya<\/option><option value=\"Liechtenstein\" data-country-code=\"LI\" >Liechtenstein<\/option><option value=\"Lithuania\" data-country-code=\"LT\" >Lithuania<\/option><option value=\"Luxembourg\" data-country-code=\"LU\" >Luxembourg<\/option><option value=\"Macau\" data-country-code=\"MO\" >Macau<\/option><option value=\"North Macedonia\" data-country-code=\"MK\" >North Macedonia<\/option><option value=\"Madagascar\" data-country-code=\"MG\" >Madagascar<\/option><option value=\"Malawi\" data-country-code=\"MW\" >Malawi<\/option><option value=\"Malaysia\" data-country-code=\"MY\" >\u9a6c\u6765\u897f\u4e9a<\/option><option value=\"Maldives\" data-country-code=\"MV\" >Maldives<\/option><option value=\"Mali\" data-country-code=\"ML\" >Mali<\/option><option value=\"Malta\" data-country-code=\"MT\" >Malta<\/option><option value=\"Marshall Islands\" data-country-code=\"MH\" >Marshall Islands<\/option><option value=\"Martinique\" data-country-code=\"MQ\" >Martinique<\/option><option value=\"Mauritania\" data-country-code=\"MR\" >Mauritania<\/option><option value=\"Mauritius\" data-country-code=\"MU\" >Mauritius<\/option><option value=\"Mayotte\" data-country-code=\"YT\" >Mayotte<\/option><option value=\"Mexico\" data-country-code=\"MX\" >Mexico<\/option><option value=\"Micronesia\" data-country-code=\"FM\" >Micronesia<\/option><option value=\"Moldova\" data-country-code=\"MD\" >Moldova<\/option><option value=\"Monaco\" data-country-code=\"MC\" >Monaco<\/option><option value=\"Mongolia\" data-country-code=\"MN\" >Mongolia<\/option><option value=\"Montserrat\" data-country-code=\"MS\" >Montserrat<\/option><option value=\"Montenegro\" data-country-code=\"ME\" >Montenegro<\/option><option value=\"Morocco\" data-country-code=\"MA\" >Morocco<\/option><option value=\"Mozambique\" data-country-code=\"MZ\" >Mozambique<\/option><option value=\"Myanmar\" data-country-code=\"MM\" >Myanmar<\/option><option value=\"Namibia\" data-country-code=\"NA\" >Namibia<\/option><option value=\"Nauru\" data-country-code=\"NR\" >Nauru<\/option><option value=\"Nepal\" data-country-code=\"NP\" >Nepal<\/option><option value=\"Netherlands\" data-country-code=\"NL\" >Netherlands<\/option><option value=\"Netherlands Antilles\" data-country-code=\"AN\" >Netherlands Antilles<\/option><option value=\"New Caledonia\" data-country-code=\"NC\" >New Caledonia<\/option><option value=\"New Zealand\" data-country-code=\"NZ\" >New Zealand<\/option><option value=\"Nicaragua\" data-country-code=\"NI\" >Nicaragua<\/option><option value=\"Niger\" data-country-code=\"NE\" >Niger<\/option><option value=\"Nigeria\" data-country-code=\"NG\" >Nigeria<\/option><option value=\"Niue\" data-country-code=\"NU\" >Niue<\/option><option value=\"Norfolk Island\" data-country-code=\"NF\" >Norfolk Island<\/option><option value=\"Northern Mariana Islands\" data-country-code=\"MP\" >Northern Mariana Islands<\/option><option value=\"Norway\" data-country-code=\"NO\" >Norway<\/option><option value=\"Oman\" data-country-code=\"OM\" >Oman<\/option><option value=\"Pakistan\" data-country-code=\"PK\" >Pakistan<\/option><option value=\"Palau\" data-country-code=\"PW\" >Palau<\/option><option value=\"Palestine, State of\" data-country-code=\"PS\" >Palestine, State of<\/option><option value=\"Panama\" data-country-code=\"PA\" >Panama<\/option><option value=\"Papua New Guinea\" data-country-code=\"PG\" >Papua New Guinea<\/option><option value=\"Paraguay\" data-country-code=\"PY\" >Paraguay<\/option><option value=\"Peru\" data-country-code=\"PE\" >Peru<\/option><option value=\"Philippines\" data-country-code=\"PH\" >Philippines<\/option><option value=\"Pitcairn Islands\" data-country-code=\"PN\" >Pitcairn Islands<\/option><option value=\"Poland\" data-country-code=\"PL\" >Poland<\/option><option value=\"Portugal\" data-country-code=\"PT\" >Portugal<\/option><option value=\"Puerto Rico\" data-country-code=\"PR\" >Puerto Rico<\/option><option value=\"Qatar\" data-country-code=\"QA\" >Qatar<\/option><option value=\"Reunion Island\" data-country-code=\"RE\" >Reunion Island<\/option><option value=\"Romania\" data-country-code=\"RO\" >Romania<\/option><option value=\"Russia\" data-country-code=\"RU\" >Russia<\/option><option value=\"Rwanda\" data-country-code=\"RW\" >Rwanda<\/option><option value=\"Saint Kitts and Nevis\" data-country-code=\"KN\" >Saint Kitts and Nevis<\/option><option value=\"Saint Lucia\" data-country-code=\"LC\" >Saint Lucia<\/option><option value=\"Saint Vincent and the Grenadines\" data-country-code=\"VC\" >Saint Vincent and the Grenadines<\/option><option value=\"Samoa\" data-country-code=\"WS\" >Samoa<\/option><option value=\"Saint Helena\" data-country-code=\"SH\" >Saint Helena<\/option><option value=\"Saint Pierre & Miquelon\" data-country-code=\"PM\" >Saint Pierre & Miquelon<\/option><option value=\"San Marino\" data-country-code=\"SM\" >San Marino<\/option><option value=\"Sao Tome and Principe\" data-country-code=\"ST\" >Sao Tome and Principe<\/option><option value=\"Saudi Arabia\" data-country-code=\"SA\" >Saudi Arabia<\/option><option value=\"Senegal\" data-country-code=\"SN\" >Senegal<\/option><option value=\"Serbia\" data-country-code=\"RS\" >Serbia<\/option><option value=\"Seychelles\" data-country-code=\"SC\" >Seychelles<\/option><option value=\"Sierra Leone\" data-country-code=\"SL\" >Sierra Leone<\/option><option value=\"Singapore\" data-country-code=\"SG\" >Singapore<\/option><option value=\"Sint Maarten\" data-country-code=\"MF\" >Sint Maarten<\/option><option value=\"Slovakia\" data-country-code=\"SK\" >Slovakia<\/option><option value=\"Slovenia\" data-country-code=\"SI\" >Slovenia<\/option><option value=\"Solomon Islands\" data-country-code=\"SB\" >Solomon Islands<\/option><option value=\"Somalia\" data-country-code=\"SO\" >Somalia<\/option><option value=\"South Africa\" data-country-code=\"ZA\" >South Africa<\/option><option value=\"South Georgia and South Sandwich\" data-country-code=\"GS\" >South Georgia and South Sandwich<\/option><option value=\"Spain\" data-country-code=\"ES\" >Spain<\/option><option value=\"Sri Lanka\" data-country-code=\"LK\" >Sri Lanka<\/option><option value=\"Stateless Persons\" data-country-code=\"XX\" >Stateless Persons<\/option><option value=\"Sudan\" data-country-code=\"SD\" >Sudan<\/option><option value=\"Sudan, South\" data-country-code=\"SS\" >Sudan, South<\/option><option value=\"Suriname\" data-country-code=\"SR\" >Suriname<\/option><option value=\"Svalbard and Jan Mayen\" data-country-code=\"SJ\" >Svalbard and Jan Mayen<\/option><option value=\"Swaziland\" data-country-code=\"SZ\" >Swaziland<\/option><option value=\"Sweden\" data-country-code=\"SE\" >Sweden<\/option><option value=\"Switzerland\" data-country-code=\"CH\" >Switzerland<\/option><option value=\"Syria\" data-country-code=\"SY\" >Syria<\/option><option value=\"Taiwan, Republic of China\" data-country-code=\"TW\" >Taiwan, Republic of China<\/option><option value=\"Tajikistan\" data-country-code=\"TJ\" >Tajikistan<\/option><option value=\"Tanzania\" data-country-code=\"TZ\" >Tanzania<\/option><option value=\"Thailand\" data-country-code=\"TH\" >\u6cf0\u56fd<\/option><option value=\"Togo\" data-country-code=\"TG\" >Togo<\/option><option value=\"Tokelau\" data-country-code=\"TK\" >Tokelau<\/option><option value=\"Tonga\" data-country-code=\"TO\" >Tonga<\/option><option value=\"Trinidad and Tobago\" data-country-code=\"TT\" >Trinidad and Tobago<\/option><option value=\"Tunisia\" data-country-code=\"TN\" >Tunisia<\/option><option value=\"Turkey\" data-country-code=\"TR\" >Turkey<\/option><option value=\"Turkmenistan\" data-country-code=\"TM\" >Turkmenistan<\/option><option value=\"Turks And Caicos Islands\" data-country-code=\"TC\" >Turks And Caicos Islands<\/option><option value=\"Tuvalu\" data-country-code=\"TV\" >Tuvalu<\/option><option value=\"Uganda\" data-country-code=\"UG\" >Uganda<\/option><option value=\"Ukraine\" data-country-code=\"UA\" >Ukraine<\/option><option value=\"United Arab Emirates\" data-country-code=\"AE\" >United Arab Emirates<\/option><option value=\"United Kingdom\" data-country-code=\"GB\" >United Kingdom<\/option><option value=\"US Minor Outlying Islands\" data-country-code=\"UM\" >US Minor Outlying Islands<\/option><option value=\"United States of America (USA)\" data-country-code=\"US\" >United States of America (USA)<\/option><option value=\"Uruguay\" data-country-code=\"UY\" >Uruguay<\/option><option value=\"Uzbekistan\" data-country-code=\"UZ\" >Uzbekistan<\/option><option value=\"Vanuatu\" data-country-code=\"VU\" >Vanuatu<\/option><option value=\"Vatican City\" data-country-code=\"VA\" >Vatican City<\/option><option value=\"Venezuela\" data-country-code=\"VE\" >Venezuela<\/option><option value=\"Vietnam\" data-country-code=\"VN\" >\u8d8a\u5357<\/option><option value=\"Virgin Islands, British\" data-country-code=\"VG\" >Virgin Islands, British<\/option><option value=\"Virgin Islands, U.S.\" data-country-code=\"VI\" >Virgin Islands, U.S.<\/option><option value=\"Wallis And Futuna Islands\" data-country-code=\"WF\" >Wallis And Futuna Islands<\/option><option value=\"Western Sahara\" data-country-code=\"EH\" >Western Sahara<\/option><option value=\"Yemen\" data-country-code=\"YE\" >Yemen<\/option><option value=\"Zambia\" data-country-code=\"ZM\" >Zambia<\/option><option value=\"Zimbabwe\" data-country-code=\"ZW\" >Zimbabwe<\/option><\/select><\/div><\/div><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"email-1\" class=\"forminator-field-email forminator-col forminator-col-12\"><div class=\"forminator-field\"><label for=\"forminator-field-email-1_6a97b09180aee\" id=\"forminator-field-email-1_6a97b09180aee-label\" class=\"forminator-label\">\u7535\u5b50\u90ae\u4ef6\u5730\u5740 <span class=\"forminator-required\">*<\/span><\/label><input type=\"email\" name=\"email-1\" value=\"\" placeholder=\"E.g. john@doe.com\" id=\"forminator-field-email-1_6a97b09180aee\" class=\"forminator-input forminator-email--field\" data-required=\"1\" aria-required=\"true\" \/><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"phone-1\" class=\"forminator-field-phone forminator-col forminator-col-12\"><div class=\"forminator-field\"><label for=\"forminator-field-phone-1_6a97b09180aee\" id=\"forminator-field-phone-1_6a97b09180aee-label\" class=\"forminator-label\">\u7535\u8bdd\u53f7\u7801<\/label><input type=\"text\" name=\"phone-1\" value=\"\" placeholder=\"E.g. +65 9123 4567\" id=\"forminator-field-phone-1_6a97b09180aee\" class=\"forminator-input forminator-field--phone\" data-required=\"\" aria-required=\"false\" autocomplete=\"off\" \/><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"textarea-1\" class=\"forminator-field-textarea forminator-col forminator-col-12\"><div class=\"forminator-field\"><label for=\"forminator-field-textarea-1_6a97b09180aee\" id=\"forminator-field-textarea-1_6a97b09180aee-label\" class=\"forminator-label\">\u54a8\u8be2\u8be6\u60c5 <span class=\"forminator-required\">*<\/span><\/label><textarea name=\"textarea-1\" placeholder=\"Enter your message...\" id=\"forminator-field-textarea-1_6a97b09180aee\" class=\"forminator-textarea\" rows=\"6\" style=\"min-height:140px;\" maxlength=\"180\" ><\/textarea><span id=\"forminator-field-textarea-1_6a97b09180aee-description\" class=\"forminator-description\"><span data-limit=\"180\" data-type=\"characters\">0 \/ 180<\/span><\/span><\/div><\/div><\/div><input type=\"hidden\" name=\"referer_url\" value=\"\" \/><div class=\"forminator-row forminator-row-last\"><div class=\"forminator-col\"><div class=\"forminator-field\"><button class=\"forminator-button forminator-button-submit\">\u63d0\u4ea4<\/button><\/div><\/div><\/div><input type=\"hidden\" id=\"forminator_nonce\" name=\"forminator_nonce\" value=\"2ad8405bac\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/zh\/wp-json\/wp\/v2\/pages\/15\" \/><input type=\"hidden\" name=\"form_id\" value=\"146\"><input type=\"hidden\" name=\"page_id\" value=\"15\"><input type=\"hidden\" name=\"form_type\" value=\"default\"><input type=\"hidden\" name=\"current_url\" value=\"https:\/\/bartengroup.com\/zh\/contact\/\"><input type=\"hidden\" name=\"render_id\" value=\"0\"><input type=\"hidden\" name=\"action\" value=\"forminator_submit_form_custom-forms\"><input type=\"hidden\" name=\"trp-form-language\" value=\"zh\"\/><\/form><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-2 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<h4 class=\"wp-block-heading has-text-align-left hestia-title has-text-color\" style=\"color:#3c4858;font-size:18px\"><img decoding=\"async\" class=\"wp-image-86\" style=\"width: 25px;\" src=\"https:\/\/bartengroup.com\/wp-content\/themes\/hestia\/assets\/img\/contact1.png\" alt=\"Map icon\">  <strong>\u5728\u529e\u516c\u5ba4\u627e\u5230\u6211\u4eec<\/strong><\/h4>\n\n\n\n<p class=\"has-text-align-left has-text-color\" style=\"color:#999999;font-size:14px\">18 Boon Lay Way,<br>#08-113, TradeHub 21<br>Singapore 609966<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-left hestia-title has-text-color\" style=\"color:#3c4858;font-size:18px\"><img decoding=\"async\" class=\"wp-image-98\" style=\"width: 25px;\" src=\"https:\/\/bartengroup.com\/wp-content\/themes\/hestia\/assets\/img\/contact2.png\" alt=\"\">  <strong><strong>\u7ed9\u6211\u4eec\u6253\u7535\u8bdd<\/strong><\/strong><\/h4>\n\n\n\n<p class=\"has-text-align-left has-text-color\" style=\"color:#999999;font-size:14px\">Steven Wu<br>+65 9029 6989<br>Mon &#8211; Fri, 8:00-17:00<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-left hestia-title has-text-color\" style=\"color:#3c4858;font-size:18px\"><img decoding=\"async\" class=\"wp-image-105\" style=\"width: 25px;\" src=\"https:\/\/bartengroup.com\/wp-content\/themes\/hestia\/assets\/img\/contact3.png\" alt=\"\"><strong>  <strong>\u91d1\u878d | \u6295\u8d44 <\/strong><\/strong><\/h4>\n\n\n\n<p class=\"has-text-align-left has-text-color\" style=\"color:#999999;font-size:14px\">Matthew Lee<br>+65 9761 4913<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Send us a message Find us at the office 18 Boon Lay Way,#08-113, TradeHub 21Singapore 609966 Give us a ring Steven Wu+65 9029 6989Mon &#8211; Fri, 8:00-17:00 Finance | Investment Matthew Lee+65 9761 4913<\/p>","protected":false},"author":1,"featured_media":7,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/template-pagebuilder-full-width.php","meta":{"ub_ctt_via":"","footnotes":""},"featured_image_src":"https:\/\/bartengroup.com\/wp-content\/uploads\/2024\/04\/contact.jpg","_links":{"self":[{"href":"https:\/\/bartengroup.com\/zh\/wp-json\/wp\/v2\/pages\/15"}],"collection":[{"href":"https:\/\/bartengroup.com\/zh\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bartengroup.com\/zh\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bartengroup.com\/zh\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bartengroup.com\/zh\/wp-json\/wp\/v2\/comments?post=15"}],"version-history":[{"count":12,"href":"https:\/\/bartengroup.com\/zh\/wp-json\/wp\/v2\/pages\/15\/revisions"}],"predecessor-version":[{"id":150,"href":"https:\/\/bartengroup.com\/zh\/wp-json\/wp\/v2\/pages\/15\/revisions\/150"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bartengroup.com\/zh\/wp-json\/wp\/v2\/media\/7"}],"wp:attachment":[{"href":"https:\/\/bartengroup.com\/zh\/wp-json\/wp\/v2\/media?parent=15"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}